{"id":55106,"date":"2025-01-26T04:41:00","date_gmt":"2025-01-26T01:41:00","guid":{"rendered":"https:\/\/nookhba.store\/product\/%d8%ab%d9%84%d8%a7%d8%ac%d8%a9-%d8%a7%d9%84-%d8%ac%d9%8a-gnb-542gvwp-%d8%a8%d9%81%d8%b1%d9%8a%d8%b2%d8%b1-%d8%b9%d9%84%d9%88%d9%8a-360-%d9%84%d8%aa%d8%b1%d8%8c-%d8%a7%d8%a8%d9%8a%d8%b6\/"},"modified":"2025-01-26T04:41:00","modified_gmt":"2025-01-26T01:41:00","slug":"%d8%ab%d9%84%d8%a7%d8%ac%d8%a9-%d8%a7%d9%84-%d8%ac%d9%8a-gnb-542gvwp-%d8%a8%d9%81%d8%b1%d9%8a%d8%b2%d8%b1-%d8%b9%d9%84%d9%88%d9%8a-360-%d9%84%d8%aa%d8%b1%d8%8c-%d8%a7%d8%a8%d9%8a%d8%b6","status":"publish","type":"product","link":"https:\/\/nookhba.store\/ar\/product\/%d8%ab%d9%84%d8%a7%d8%ac%d8%a9-%d8%a7%d9%84-%d8%ac%d9%8a-gnb-542gvwp-%d8%a8%d9%81%d8%b1%d9%8a%d8%b2%d8%b1-%d8%b9%d9%84%d9%88%d9%8a-360-%d9%84%d8%aa%d8%b1%d8%8c-%d8%a7%d8%a8%d9%8a%d8%b6\/","title":{"rendered":"\u062b\u0644\u0627\u062c\u0629 \u0627\u0644 \u062c\u064a GNB-542GVWP \u0628\u0641\u0631\u064a\u0632\u0631 \u0639\u0644\u0648\u064a 360 \u0644\u062a\u0631\u060c \u0627\u0628\u064a\u0636"},"content":{"rendered":"<h2>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0645\u0646\u062a\u062c<\/h2>\n<div class=\"seo-optimized\">\n<p class=\"seo-optimized\">  \u062b\u0644\u0627\u062c\u0629 \u0628\u0628\u0627\u0628 \u0645\u0632\u062f\u0648\u062c \u0645\u0646 LG<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0627\u0644\u0633\u0639\u0629: 360 \u0644\u062a\u0631<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0645\u0627\u062f\u0629 \u0627\u0644\u0631\u0641\u0648\u0641: \u0632\u062c\u0627\u062c \u0645\u0642\u0648\u0649<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0646\u0648\u0639 \u0627\u0644\u0645\u0628\u0631\u062f: \u0644\u0627 \u0641\u0631\u0648\u0633\u062a<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0646\u0648\u0639 \u0627\u0644\u0645\u0642\u0628\u0636: \u0628\u0644\u0627\u0633\u062a\u064a\u0643<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0646\u0648\u0639 \u063a\u0627\u0632 \u0627\u0644\u062a\u0628\u0631\u064a\u062f: R600a<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0636\u0627\u063a\u0637 \u0627\u0644\u0639\u0627\u0643\u0633: BSA075NHMV<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0627\u0644\u0645\u064a\u0632\u0627\u062a: \u0625\u0646\u0630\u0627\u0631 \u0627\u0644\u0628\u0627\u0628 \u060c \u062c\u0647\u0627\u0632 \u0627\u0644\u062a\u062d\u0643\u0645 \u0641\u064a \u062f\u0631\u062c\u0629 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u060c \u0627\u0644\u062a\u0646\u0628\u064a\u0647 \u0639\u0646\u062f \u062a\u0631\u0643 \u0627\u0644\u0628\u0627\u0628 \u0645\u0641\u062a\u0648\u062d\u0627<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0627\u0644\u0623\u0628\u0639\u0627\u062f: 710 \u00d7 1720 \u00d7 600 \u0645\u0644\u0645<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0627\u0644\u0648\u0632\u0646: 66 \u0643\u062c\u0645<\/p>\n<p><\/p>\n<p class=\"seo-optimized\">  \u0627\u0644\u0644\u0648\u0646 \u0623\u0628\u064a\u0636<\/p>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0645\u0646\u062a\u062c \u062b\u0644\u0627\u062c\u0629 \u0628\u0628\u0627\u0628 \u0645\u0632\u062f\u0648\u062c \u0645\u0646 LG \u0627\u0644\u0633\u0639\u0629: 360 \u0644\u062a\u0631 \u0645\u0627\u062f\u0629 \u0627\u0644\u0631\u0641\u0648\u0641: \u0632\u062c\u0627\u062c \u0645\u0642\u0648\u0649 \u0646\u0648\u0639 [&hellip;]<\/p>\n","protected":false},"featured_media":35960,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2450],"product_tag":[3422,3423,2449,3424,2513,2441],"class_list":["post-55106","product","type-product","status-publish","has-post-thumbnail","product_cat-2450","product_tag-gnb-542gvwp-ar","product_tag-top-ar","product_tag-2449","product_tag-3424","product_tag-2513","product_tag--ar","first","instock","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product\/55106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/comments?post=55106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/media\/35960"}],"wp:attachment":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/media?parent=55106"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product_brand?post=55106"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product_cat?post=55106"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product_tag?post=55106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}