{"id":54916,"date":"2025-01-26T04:46:44","date_gmt":"2025-01-26T01:46:44","guid":{"rendered":"https:\/\/nookhba.store\/product\/%d9%84%d9%88%d8%ad%d8%a9-%d9%85%d9%81%d8%a7%d8%aa%d9%8a%d8%ad-%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-%d8%a7%d9%84%d9%84%d8%a7%d8%b3%d9%84%d9%83%d9%8a%d8%a9-log\/"},"modified":"2025-01-26T04:46:44","modified_gmt":"2025-01-26T01:46:44","slug":"%d9%84%d9%88%d8%ad%d8%a9-%d9%85%d9%81%d8%a7%d8%aa%d9%8a%d8%ad-%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-%d8%a7%d9%84%d9%84%d8%a7%d8%b3%d9%84%d9%83%d9%8a%d8%a9-log","status":"publish","type":"product","link":"https:\/\/nookhba.store\/ar\/product\/%d9%84%d9%88%d8%ad%d8%a9-%d9%85%d9%81%d8%a7%d8%aa%d9%8a%d8%ad-%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-%d8%a7%d9%84%d9%84%d8%a7%d8%b3%d9%84%d9%83%d9%8a%d8%a9-log\/","title":{"rendered":"\u0644\u0648\u062d\u0629 \u0645\u0641\u0627\u062a\u064a\u062d \u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0627\u0644\u0644\u0627\u0633\u0644\u0643\u064a\u0629 Logitech K750"},"content":{"rendered":"<h2>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0645\u0646\u062a\u062c<\/h2>\n<div class=\"seo-optimized\">\n<p class=\"seo-optimized\">\u0644\u0648\u062d\u0629 \u0645\u0641\u0627\u062a\u064a\u062d \u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0627\u0644\u0644\u0627\u0633\u0644\u0643\u064a\u0629 Logitech K750<\/p>\n<p><img decoding=\"async\" class=\"seo-optimized\" src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media\/vc\/766c9f93-a744-4f29-badb-a72eae3cd0a8._CR0,0,1464,600_PT0_SX1464__.jpg\" alt=\"\u0643 750\"><\/p>\n<p class=\"seo-optimized\">\n<p><\/p>\n<p class=\"seo-optimized\">\u0642\u0644 \u0648\u062f\u0627\u0639\u0627 \u0644\u0645\u062a\u0627\u0639\u0628 \u0627\u0644\u0628\u0637\u0627\u0631\u064a\u0629. \u0623\u064a \u0645\u0635\u062f\u0631 \u0636\u0648\u0621 \u064a\u062d\u0627\u0641\u0638 \u0639\u0644\u0649 K750 \u0645\u0634\u062d\u0648\u0646\u0627 \u0648\u062c\u0627\u0647\u0632\u0627. \u064a\u0636\u064a\u0641 \u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0627\u0646\u0633\u064a\u0627\u0628\u064a \u0623\u0633\u0644\u0648\u0628\u0627 \u0623\u0646\u064a\u0642\u0627 \u0625\u0644\u0649 \u0645\u0633\u0627\u062d\u0629 \u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u060c \u0648\u0642\u062f \u062a\u0645 \u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0645\u0641\u0627\u062a\u064a\u062d \u0644\u0644\u0643\u062a\u0627\u0628\u0629 \u0627\u0644\u0645\u0631\u064a\u062d\u0629 \u0633\u0627\u0639\u0629 \u0628\u0639\u062f \u0633\u0627\u0639\u0629.  <\/p>\n<p><\/p>\n<p class=\"seo-optimized\">\u062a\u0634\u062d\u0646 \u0644\u0648\u062d\u0629 \u0627\u0644\u0645\u0641\u0627\u062a\u064a\u062d \u0646\u0641\u0633\u0647\u0627 \u0628\u0645\u0635\u0628\u0627\u062d \u0623\u0648 \u0636\u0648\u0621 \u0627\u0644\u0634\u0645\u0633. \u0631\u0627\u0642\u0628 \u0628\u0633\u0647\u0648\u0644\u0629 \u0645\u0633\u062a\u0648\u0649 \u0637\u0627\u0642\u062a\u0643 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062a\u0637\u0628\u064a\u0642 Logitech Solar. <\/p>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<h3>\u062f\u0644\u0627\u0626\u0644 \u0627\u0644\u0645\u064a\u0632\u0627\u062a:<\/h3>\n<ul>\n<li><strong>\u0648\u0633\u0645:<\/strong> \u0644\u0648\u062c\u064a\u062a\u0643<\/li>\n<li><strong>\u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u0645\u062a\u0648\u0627\u0641\u0642\u0629:<\/strong> \u0643\u0645\u0628\u064a\u0648\u062a\u0631 \u0634\u062e\u0635\u064a<\/li>\n<li><strong>\u062a\u0642\u0646\u064a\u0629 \u0627\u0644\u0627\u062a\u0635\u0627\u0644:<\/strong> \u0644\u0627\u0633\u0644\u0643\u064a<\/li>\n<li><strong>\u0648\u0635\u0641 \u0644\u0648\u062d\u0629 \u0627\u0644\u0645\u0641\u0627\u062a\u064a\u062d:<\/strong> \u0644\u0627\u0633\u0644\u0643\u064a<\/li>\n<li><strong>\u0645\u064a\u0632\u0629 \u062e\u0627\u0635\u0629:<\/strong> \u0644\u0627\u0633\u0644\u0643\u064a<\/li>\n<li><strong>\u0644\u0648\u0646:<\/strong> \u0623\u0633\u0648\u062f<\/li>\n<li><strong>\u0646\u0638\u0627\u0645 \u0627\u0644\u062a\u0634\u063a\u064a\u0644:<\/strong> Windows 10 \u0623\u0648 11 \u0623\u0648 \u0623\u062d\u062f\u062b<\/li>\n<li><strong>\u0646\u0645\u0637:<\/strong> \u0628\u062f\u0648\u0646 \u0645\u0627\u0648\u0633<\/li>\n<li><strong>\u0623\u0628\u0639\u0627\u062f \u0627\u0644\u0633\u0644\u0639\u0629 LxWxH:<\/strong> 7.87 \u00d7 1.38 \u00d7 19.09 \u0628\u0648\u0635\u0629<\/li>\n<li><strong>\u0627\u0644\u0645\u0643\u0648\u0646\u0627\u062a \u0627\u0644\u0645\u0636\u0645\u0646\u0629:<\/strong> \u0643\u0627\u0628\u0644 USB<\/li>\n<\/ul>\n<\/ul>\n","protected":false},"featured_media":35642,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2488,2492,2493],"product_tag":[3045,2605,3040,3042,2909],"class_list":["post-54916","product","type-product","status-publish","has-post-thumbnail","product_cat-2488","product_cat---ar","product_cat-2493","product_tag-3045","product_tag-2605","product_tag---logitech-","product_tag-3042","product_tag-2909","first","instock","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product\/54916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/comments?post=54916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/media\/35642"}],"wp:attachment":[{"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/media?parent=54916"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product_brand?post=54916"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product_cat?post=54916"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nookhba.store\/ar\/wp-json\/wp\/v2\/product_tag?post=54916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}